<br />
<b>Warning</b>:  file_exists(): open_basedir restriction in effect. File(/home/archart/domains/archart.ir/public_html/blog/wp-content/plugins/wp-rocket/) is not within the allowed path(s): (/home/h379408/:/tmp:/var/tmp:/opt/alt/php81/usr/share/pear/:/dev/urandom:/usr/local/lib/php/:/usr/local/php81/lib/php/) in <b>/home/h379408/domains/archart.ir/public_html/blog/wp-content/advanced-cache.php</b> on line <b>17</b><br />
{"id":1529,"date":"2019-12-24T12:20:49","date_gmt":"2019-12-24T08:50:49","guid":{"rendered":"https:\/\/archart.ir\/blog\/%d8%a2%d9%85%d9%88%d8%b2%d8%b4-%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%da%a9%d8%a7%d8%a8%db%8c%d9%86%d8%aa-%d8%af%d8%b1-%d8%a7%d8%aa%d9%88%da%a9%d8%af-%d9%88-%d8%aa%d8%b1%db%8c-%d8%af%db%8c-%d9%85%da%a9%d8%b3\/"},"modified":"2022-01-24T09:10:00","modified_gmt":"2022-01-24T05:40:00","slug":"%d8%a2%d9%85%d9%88%d8%b2%d8%b4-%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%da%a9%d8%a7%d8%a8%db%8c%d9%86%d8%aa-%d8%af%d8%b1-%d8%a7%d8%aa%d9%88%da%a9%d8%af-%d9%88-%d8%aa%d8%b1%db%8c-%d8%af%db%8c-%d9%85%da%a9%d8%b3","status":"publish","type":"post","link":"https:\/\/archart.ir\/blog\/%d8%a2%d9%85%d9%88%d8%b2%d8%b4-%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%da%a9%d8%a7%d8%a8%db%8c%d9%86%d8%aa-%d8%af%d8%b1-%d8%a7%d8%aa%d9%88%da%a9%d8%af-%d9%88-%d8%aa%d8%b1%db%8c-%d8%af%db%8c-%d9%85%da%a9%d8%b3\/","title":{"rendered":"\u0622\u0645\u0648\u0632\u0634 \u0637\u0631\u0627\u062d\u06cc \u06a9\u0627\u0628\u06cc\u0646\u062a \u062f\u0631 \u0627\u062a\u0648\u06a9\u062f \u0648 \u062a\u0631\u06cc \u062f\u06cc \u0645\u06a9\u0633 \u0642\u0633\u0645\u062a \u0627\u0648\u0644"},"content":{"rendered":"\n<div id=\"19167403118\"><script type=\"text\/JavaScript\" src=\"https:\/\/www.aparat.com\/embed\/5dX2V?data[rnddiv]=19167403118&amp;data[responsive]=yes\"><\/script><\/div>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n<div class=\"col-12 col-lg-9 mt-3\">\n<div class=\"dirRtl TAR text-justify\" data-aos=\"fade-up\">\n<h1 id=\"videoTitle\"><\/h1>\n<p style=\"text-align: justify\">\u062f\u0631 \u0627\u06cc\u0646 \u0642\u0633\u0645\u062a \u0627\u0632 \u0622\u0645\u0648\u0632\u0634 \u0645\u06cc \u062e\u0648\u0627\u0647\u06cc\u0645 \u0628\u0628\u06cc\u0646\u06cc\u0645 \u0686\u06af\u0648\u0646\u0647 \u0628\u0627\u06cc\u062f \u06cc\u06a9 \u06a9\u0627\u0628\u06cc\u0646\u062a \u0631\u0627 \u0637\u0628\u0642 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0647\u0627 \u0637\u0631\u0627\u062d\u06cc \u06a9\u0646\u06cc\u0645 \u0637\u0631\u0627\u062d\u06cc \u06a9\u0627\u0628\u06cc\u0646\u062a \u06cc\u06a9\u0633\u0631\u06cc \u062a\u0631\u0641\u0646\u062f \u0647\u0627 \u062f\u0627\u0631\u062f. \u0628\u0627\u06cc\u062f \u0628\u062f\u0648\u0646\u06cc\u062f \u0628\u0647 \u0637\u0648\u0631 \u0645\u062b\u0627\u0644 \u0627\u0646\u062f\u0627\u0632\u0647 \u0647\u0627\u06cc \u067e\u0627\u062e\u0648\u0631 \u0648 \u06a9\u0627\u0628\u06cc\u0646\u062a \u0647\u0627\u06cc \u0632\u0645\u06cc\u0646\u06cc \u0648 \u0647\u0648\u0627\u06cc\u06cc \u0628\u0647 \u0686\u0647 \u0635\u0648\u0631\u062a \u0645\u06cc \u0628\u0627\u0634\u0646\u062f. \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u06cc\u06a9 \u0637\u0631\u0627\u062d\u06cc \u0632\u06cc\u0628\u0627 \u0648 \u0645\u0648\u0641\u0642 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f. \u067e\u0633&nbsp; \u0648\u06cc\u062f\u0626\u0648 \u0622\u0645\u0648\u0632\u0634\u06cc \u0627\u06cc\u0646 \u0628\u062e\u0634 \u06a9\u0647 \u062f\u0627\u0631\u0627\u06cc \u062f\u0648 \u0642\u0633\u0645\u062a \u0645\u06cc \u0628\u0627\u0634\u062f \u0631\u0627 \u0627\u0632 \u062f\u0633\u062a \u0646\u062f\u0647\u06cc\u062f.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/archart.ir\/blog\/wp-content\/uploads\/2022\/01\/1577265365_k1.jpg\" alt=\"\" title=\"\"><\/p>\n<p><img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/archart.ir\/blog\/wp-content\/uploads\/2022\/01\/1577265371_k2.jpg\" alt=\"\" title=\"\"><\/p>\n<p><img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/archart.ir\/blog\/wp-content\/uploads\/2022\/01\/1577265539_k3.jpg\" alt=\"\" title=\"\"><\/p>\n<h2>\u0645\u062d\u062a\u0648\u0627:<\/h2>\n<p style=\"text-align: justify\">\u0645\u0627&nbsp; \u062f\u0631 \u0627\u06cc\u0646 \u0648\u06cc\u062f\u0626\u0648 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0646\u06a9\u0627\u062a \u0637\u0631\u0627\u062d\u06cc \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0631\u0627 \u062f\u0631 \u0646\u0631\u0645 \u0627\u0641\u0632\u0627\u0631 <strong><a href=\"https:\/\/archart.ir\/Course\/1\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%86%D8%B1%D9%85-%D8%A7%D9%81%D8%B2%D8%A7%D8%B1-%D8%A7%D8%AA%D9%88%DA%A9%D8%AF-%D8%AF%D9%88-%D8%A8%D8%B9%D8%AF%DB%8C\/\">\u0627\u062a\u0648\u06a9\u062f<\/a><\/strong> \u0645\u06cc \u06af\u0648\u06cc\u06cc\u0645 \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u062f\u0631 \u06a9\u0646\u0627\u0631 \u062f\u0627\u0634\u062a\u0646 \u06cc\u06a9 \u0637\u0631\u0627\u062d\u06cc \u062e\u0648\u0628 \u06cc\u06a9 \u0622\u0634\u067e\u0632\u062e\u0627\u0646\u0647 \u0631\u0627\u062d\u062a \u0648 \u062f\u0648\u0633\u062a \u062f\u0627\u0634\u062a\u0646\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f. \u062f\u0631 \u0627\u0628\u062a\u062f\u0627 \u0628\u0647 \u0634\u0645\u0627 \u0645\u06cc \u06af\u0648\u06cc\u06cc\u0645 \u06a9\u0647 \u0627\u0631\u062a\u0641\u0627\u0639 \u0648 \u0639\u0645\u0642&nbsp; \u06a9\u0627\u0628\u06cc\u0646\u062a \u0647\u0627\u06cc \u0632\u0645\u06cc\u0646\u06cc \u0648 \u0647\u0648\u0627\u06cc \u0628\u0647 \u0686\u0647 \u0635\u0648\u0631\u062a \u0628\u0627\u0634\u0646\u062f \u0648 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0686\u0646\u062f \u06a9\u0627\u0628\u06cc\u0646\u062a \u0631\u0627 \u0628\u0627 \u0647\u0645 \u0628\u0631\u0631\u0633\u06cc \u0645\u06cc \u06a9\u0646\u06cc\u0645. \u0634\u0645\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0627 \u0647\u0645\u0631\u0627\u0647\u06cc \u06a9\u0631\u062f\u0646 \u0627\u06cc\u0646 \u0622\u0645\u0648\u0632\u0634 \u06a9\u0627\u0628\u06cc\u0646\u062a \u0647\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u062f\u0631 <strong><a href=\"https:\/\/archart.ir\/Course\/1\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%86%D8%B1%D9%85-%D8%A7%D9%81%D8%B2%D8%A7%D8%B1-%D8%A7%D8%AA%D9%88%DA%A9%D8%AF-%D8%AF%D9%88-%D8%A8%D8%B9%D8%AF%DB%8C\/\">\u0627\u062a\u0648\u06a9\u062f<\/a><\/strong> \u0637\u0631\u0627\u062d\u06cc \u0648 \u062f\u0631 \u062c\u0627\u06cc\u06af\u0627\u0647 \u0647\u0627\u06cc \u062e\u0648\u062f \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u062f \u062a\u0627 \u062f\u0631 \u062c\u0644\u0633\u0647 \u0628\u0639\u062f \u0622\u0646 \u0647\u0627 \u0631\u0627 \u062f\u0631 \u0645\u062d\u06cc\u0637 \u0646\u0631\u0645 \u0627\u0641\u0632\u0627\u0631 <strong><a href=\"https:\/\/archart.ir\/Course\/2\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%85%D8%AF%D9%84-%D8%B3%D8%A7%D8%B2%DB%8C-%D9%86%D8%B1%D9%85-%D8%A7%D9%81%D8%B2%D8%A7%D8%B1-%D8%AA%D8%B1%DB%8C-%D8%AF%DB%8C-%D9%85%DA%A9%D8%B3\/\">\u062a\u0631\u06cc \u062f\u06cc \u0645\u06a9\u0633<\/a><\/strong> \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u0645 \u0648 \u0633\u0647 \u0628\u0639\u062f\u06cc \u0622\u0646 \u0631\u0627&nbsp; \u0628\u0627 \u06cc\u06a9\u062f\u06cc\u06af\u0631 \u0622\u0645\u0648\u0632\u0634 \u0645\u06cc \u0628\u06cc\u0646\u06cc\u0645.<\/p>\n<p>\u0642\u0633\u0645\u062a \u062f\u0648\u0645 \u0627\u06cc\u0646 \u0648\u06cc\u062f\u0626\u0648 \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0631\u0627 \u0641\u0631\u0627\u0645\u0648\u0634 \u0646\u06a9\u0646\u06cc\u062f.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify\">\u062a\u0648\u0635\u06cc\u0647 :<\/h2>\n<p>\u0633\u0627\u06cc\u062a \u0622\u0631\u0686 \u0622\u0631\u062a \u0634\u0627\u0645\u0644 <strong><a href=\"https:\/\/archart.ir\/PostByCat\/5\/%D9%88%DB%8C%D8%AF%D8%A6%D9%88-%D9%87%D8%A7%DB%8C-%D8%A2%D9%85%D9%88%D8%B2%D8%B4%DB%8C\">\u0648\u06cc\u062f\u0626\u0648\u0647\u0627\u06cc \u0622\u0645\u0648\u0632\u0634\u06cc&nbsp; <\/a><\/strong>\u0641\u0648\u0642 \u0627\u0644\u0639\u0627\u062f\u0647 \u0627\u06cc \u0627\u0632 \u0646\u0631\u0645 \u0627\u0641\u0632\u0627\u0631 \u0647\u0627\u06cc <strong><a href=\"https:\/\/archart.ir\/Course\/2\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%85%D8%AF%D9%84-%D8%B3%D8%A7%D8%B2%DB%8C-%D9%86%D8%B1%D9%85-%D8%A7%D9%81%D8%B2%D8%A7%D8%B1-%D8%AA%D8%B1%DB%8C-%D8%AF%DB%8C-%D9%85%DA%A9%D8%B3\/\">\u062a\u0631\u06cc \u062f\u06cc \u0645\u06a9\u0633 <\/a><\/strong>\u060c <strong><a href=\"https:\/\/archart.ir\/Course\/4\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%BE%D8%B1%D8%B2%D8%A7%D9%86%D8%AA%D9%87-%D8%A8%D9%87-%D9%88%D8%B3%DB%8C%D9%84%D9%87-%DB%8C-%D9%81%D8%AA%D9%88%D8%B4%D8%A7%D9%BE-2020\/\">\u0641\u062a\u0648\u0634\u0627\u0628<\/a><\/strong> \u062f\u0631 \u0632\u0645\u06cc\u0646\u0647 <strong><a href=\"https:\/\/archart.ir\/Course\/5\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%BE%D8%B3%D8%AA-%D9%BE%D8%B1%D9%88%D8%AF%D8%A7%DA%A9%D8%B4%D9%86\/\">\u067e\u0633\u062a \u067e\u0631\u0648 \u062f\u0627\u06a9\u0634\u0646<\/a><\/strong> \u0648<strong><a href=\"https:\/\/archart.ir\/Course\/4\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%BE%D8%B1%D8%B2%D8%A7%D9%86%D8%AA%D9%87-%D8%A8%D9%87-%D9%88%D8%B3%DB%8C%D9%84%D9%87-%DB%8C-%D9%81%D8%AA%D9%88%D8%B4%D8%A7%D9%BE-2020\/\"> \u067e\u0631\u0632\u0627\u0646\u062a\u0647<\/a><\/strong> \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 <strong><a href=\"https:\/\/archart.ir\/Course\/1\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%86%D8%B1%D9%85-%D8%A7%D9%81%D8%B2%D8%A7%D8%B1-%D8%A7%D8%AA%D9%88%DA%A9%D8%AF-%D8%AF%D9%88-%D8%A8%D8%B9%D8%AF%DB%8C\/\">\u0627\u062a\u0648\u06a9\u062f<\/a><\/strong> \u0645\u06cc \u0628\u0627\u0634\u062f. \u0627\u06af\u0631 \u0645\u06cc\u062e\u0648\u0627\u06cc\u062f \u0645\u0647\u0627\u0631\u062a \u062e\u0648\u062f \u0631\u0627 \u0628\u0627\u0644\u0627 \u0628\u0628\u0631\u06cc\u062f \u0648 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u06a9\u0627\u0631 \u0631\u0627\u062d\u062a \u062a\u0631 \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u06a9\u0627\u0631 \u06a9\u0646\u06cc\u062f \u0627\u0632 \u0622\u0645\u0648\u0634 \u0647\u0627\u06cc \u0633\u0627\u06cc\u062a <strong><a href=\"https:\/\/archart.ir\/\">archart<\/a><\/strong>&nbsp; \u062f\u06cc\u062f\u0646 \u06a9\u0646\u06cc\u062f.<\/p>\n<p>\u0631\u0627\u0633\u062a\u06cc!!!!!!!!!!!!!!!&nbsp; \u0622\u0645\u0648\u0632\u0634 \u0646\u0635\u0628 \u067e\u0644\u0627\u06af\u06cc\u0646 V &#8211; Ray \u0631\u0627 \u0627\u0632 \u062f\u06cc\u062a \u0646\u062f\u0647\u06cc\u062f \u0686\u0648\u0646 \u0628\u0647 \u0635\u0648\u0631\u062a \u06a9\u0627\u0645\u0644\u0627 \u0633\u0627\u062f\u0647 \u0648 \u0631\u0648\u0627\u0646 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0639\u0632\u06cc\u0632\u0627\u0646 \u0627\u06cc\u0646 \u0622\u0645\u0648\u0632\u0634 \u0646\u0635\u0628 \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u06a9\u0631\u062f\u0647 \u0627\u06cc\u0645.<\/p>\n<h1 class=\"arch-FontSizeH1\"><\/h1>\n<h2 style=\"text-align: justify\"><span title=\"\"><strong>\u0645\u0648\u0627\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647:<\/strong><\/span><\/h2>\n<p style=\"text-align: justify\">\u0627\u06cc\u0646 \u0622\u0645\u0648\u0632\u0634 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0628\u0631\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0637\u0631\u0627\u062d\u0627\u0646 \u062f\u0627\u062e\u0644\u06cc \u0648 \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u0628\u0627 \u0646\u0631\u0645 \u0627\u0641\u0632\u0627\u0631 \u0647\u0627\u06cc\u06cc \u0645\u0627\u0646\u0646\u062f <strong><a href=\"https:\/\/archart.ir\/Course\/2\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%85%D8%AF%D9%84-%D8%B3%D8%A7%D8%B2%DB%8C-%D9%86%D8%B1%D9%85-%D8%A7%D9%81%D8%B2%D8%A7%D8%B1-%D8%AA%D8%B1%DB%8C-%D8%AF%DB%8C-%D9%85%DA%A9%D8%B3\/\">\u062a\u0631\u06cc \u062f\u06cc \u0645\u06a9\u0633 <\/a><\/strong>\u060c <strong><a href=\"https:\/\/archart.ir\/Course\/7\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D8%B1%D9%88%DB%8C%D8%AA-2020-(-%D9%BE%DA%A9-%D8%AC%D8%A7%D9%85%D8%B9-%D8%B1%D9%88%DB%8C%D8%AA-)\/\">\u0631\u0648\u06cc\u062a<\/a><\/strong>\u060c <strong><a href=\"https:\/\/archart.ir\/Course\/1\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%86%D8%B1%D9%85-%D8%A7%D9%81%D8%B2%D8%A7%D8%B1-%D8%A7%D8%AA%D9%88%DA%A9%D8%AF-%D8%AF%D9%88-%D8%A8%D8%B9%D8%AF%DB%8C\/\">\u0627\u062a\u0648\u06a9\u062f <\/a><\/strong>\u0648 <strong><a href=\"https:\/\/archart.ir\/Course\/4\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%BE%D8%B1%D8%B2%D8%A7%D9%86%D8%AA%D9%87-%D8%A8%D9%87-%D9%88%D8%B3%DB%8C%D9%84%D9%87-%DB%8C-%D9%81%D8%AA%D9%88%D8%B4%D8%A7%D9%BE-2020\/\">\u0641\u062a\u0648\u0634\u0627\u067e <\/a><\/strong>\u06a9\u0627\u0631 \u0645\u06cc \u06a9\u0646\u0646\u062f \u0645\u0641\u06cc\u062f \u0628\u0627\u0634\u062f \u0686\u0631\u0627 \u06a9\u0647 \u06cc\u06a9 \u0637\u0631\u0627\u062d\u06cc \u0632\u0645\u0627\u0646\u06cc \u0645\u0637\u0644\u0648\u0628 \u0628\u0647 \u0646\u0638\u0631 \u0645\u06cc \u0631\u0633\u062f \u06a9\u0647 \u062f\u0631 \u06a9\u0646\u0627\u0631 \u0632\u06cc\u0628\u0627\u06cc\u06cc \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0636\u0631\u0648\u0631\u06cc \u0646\u06cc\u0632 \u0631\u0639\u0627\u06cc\u062a \u0634\u062f\u0647 \u0628\u0627\u0634\u062f \u062a\u0627 \u0645\u062e\u0627\u0637\u0628 \u0634\u0645\u0627 \u062f\u0631 \u0622\u0646 \u0641\u0636\u0627 \u0628\u062a\u0648\u0627\u0646\u062f \u0627\u062d\u0633\u0627\u0633 \u0631\u0627\u062d\u062a\u06cc \u06a9\u0646\u062f.<\/p>\n<div id=\"86085645589\"><\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u062f\u0631 \u0627\u06cc\u0646 \u0642\u0633\u0645\u062a \u0627\u0632 \u0622\u0645\u0648\u0632\u0634 \u0645\u06cc \u062e\u0648\u0627\u0647\u06cc\u0645 \u0628\u0628\u06cc\u0646\u06cc\u0645 \u0686\u06af\u0648\u0646\u0647 \u0628\u0627\u06cc\u062f \u06cc\u06a9 \u06a9\u0627\u0628\u06cc\u0646\u062a \u0631\u0627 \u0637\u0628\u0642 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0647\u0627 \u0637\u0631\u0627\u062d\u06cc \u06a9\u0646\u06cc\u0645 \u0637\u0631\u0627\u062d\u06cc \u06a9\u0627\u0628\u06cc\u0646\u062a \u06cc\u06a9\u0633\u0631\u06cc \u062a\u0631\u0641\u0646\u062f \u0647\u0627 \u062f\u0627\u0631\u062f. \u0628\u0627\u06cc\u062f \u0628\u062f\u0648\u0646\u06cc\u062f \u0628\u0647 \u0637\u0648\u0631 \u0645\u062b\u0627\u0644 \u0627\u0646\u062f\u0627\u0632\u0647 \u0647\u0627\u06cc \u067e\u0627\u062e\u0648\u0631 \u0648 \u06a9\u0627\u0628\u06cc\u0646\u062a \u0647\u0627\u06cc \u0632\u0645\u06cc\u0646\u06cc \u0648 \u0647\u0648\u0627\u06cc\u06cc \u0628\u0647 \u0686\u0647 \u0635\u0648\u0631\u062a \u0645\u06cc \u0628\u0627\u0634\u0646\u062f. \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u06cc\u06a9 \u0637\u0631\u0627\u062d\u06cc \u0632\u06cc\u0628\u0627 \u0648 \u0645\u0648\u0641\u0642 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f. \u067e\u0633\u00a0 \u0648\u06cc\u062f\u0626\u0648 \u0622\u0645\u0648\u0632\u0634\u06cc [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":1533,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,9],"tags":[1037,1040,1041,1038,1039],"class_list":["post-1529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category---3ds-max","category---autocad","tag-1037","tag-1040","tag-1041","tag-1038","tag-1039"],"amp_enabled":false,"acf":[],"_links":{"self":[{"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/posts\/1529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/comments?post=1529"}],"version-history":[{"count":0,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/posts\/1529\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/media\/1533"}],"wp:attachment":[{"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/media?parent=1529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/categories?post=1529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/tags?post=1529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}