<br />
<b>Warning</b>:  file_exists(): open_basedir restriction in effect. File(/home/archart/domains/archart.ir/public_html/blog/wp-content/plugins/wp-rocket/) is not within the allowed path(s): (/home/h379408/:/tmp:/var/tmp:/opt/alt/php81/usr/share/pear/:/dev/urandom:/usr/local/lib/php/:/usr/local/php81/lib/php/) in <b>/home/h379408/domains/archart.ir/public_html/blog/wp-content/advanced-cache.php</b> on line <b>17</b><br />
{"id":1609,"date":"2020-01-02T12:35:39","date_gmt":"2020-01-02T09:05:39","guid":{"rendered":"https:\/\/archart.ir\/blog\/%d8%a2%d9%85%d9%88%d8%b2%d8%b4-%d9%86%d8%b5%d8%a8-%d9%be%d9%84%d8%a7%da%af%db%8c%d9%86-sigershaders-v4-1-6-3ds-max-2013-2020\/"},"modified":"2022-01-24T09:09:21","modified_gmt":"2022-01-24T05:39:21","slug":"%d8%a2%d9%85%d9%88%d8%b2%d8%b4-%d9%86%d8%b5%d8%a8-%d9%be%d9%84%d8%a7%da%af%db%8c%d9%86-sigershaders-v4-1-6-3ds-max-2013-2020","status":"publish","type":"post","link":"https:\/\/archart.ir\/blog\/%d8%a2%d9%85%d9%88%d8%b2%d8%b4-%d9%86%d8%b5%d8%a8-%d9%be%d9%84%d8%a7%da%af%db%8c%d9%86-sigershaders-v4-1-6-3ds-max-2013-2020\/","title":{"rendered":"\u0622\u0645\u0648\u0632\u0634 \u0646\u0635\u0628 \u067e\u0644\u0627\u06af\u06cc\u0646  SIGERSHADERS V4.1.6 3ds Max 2013-2020"},"content":{"rendered":"\n<div id=\"29821542376\"><script type=\"text\/JavaScript\" src=\"https:\/\/www.aparat.com\/embed\/xcygC?data[rnddiv]=29821542376&amp;data[responsive]=yes\"><\/script><\/div>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n<div class=\"col-12 col-lg-9 mt-3\">\n<div class=\"dirRtl TAR text-justify\" data-aos=\"fade-up\">\n<p dir=\"RTL\" style=\"margin: 0in 0in 8pt;text-align: justify\"><span style=\"text-align: justify\">&nbsp;SIGERSHADER (\u0633\u06cc\u062c\u0631\u0634\u06cc\u062f\u0631) \u06cc\u06a9&nbsp;\u067e\u0644\u0627\u06af\u06cc\u0646 <a href=\"https:\/\/archart.ir\/Course\/2\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%85%D8%AF%D9%84-%D8%B3%D8%A7%D8%B2%DB%8C-%D9%86%D8%B1%D9%85-%D8%A7%D9%81%D8%B2%D8%A7%D8%B1-%D8%AA%D8%B1%DB%8C-%D8%AF%DB%8C-%D9%85%DA%A9%D8%B3\/\">\u062a\u0631\u06cc \u062f\u06cc \u0645\u06a9\u0633<\/a>&nbsp;\u0628\u0631\u0627\u06cc \u0648\u0631\u0698\u0646 2013 \u062a\u0627 2020 \u0645\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u0634\u0627\u0645\u0644 \u0627\u0646\u0648\u0627\u0639 \u0645\u062a\u0631\u06cc\u0627\u0644 \u0647\u0627\u06cc \u0622\u0645\u0627\u062f\u0647 \u0628\u0631\u0627\u06cc&nbsp;<a href=\"https:\/\/archart.ir\/Course\/3\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%BE%D9%84%D8%A7%DA%AF%DB%8C%D9%86-Vray-\/\">V-Ray<\/a> \u0645\u06cc \u0628\u0627\u0634\u062f,\u062f\u0631 \u062d\u0627\u0644\u062a \u0639\u0627\u062f\u06cc \u0633\u0627\u062e\u062a \u0645\u062a\u0631\u06cc\u0627\u0644 \u0647\u0627\u06cc \u062d\u0631\u0641\u0647 \u0627\u06cc \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0632\u0645\u0627\u0646 \u0648 \u062a\u062c\u0631\u0628\u0647 \u062e\u06cc\u0644\u06cc \u0632\u06cc\u0627\u062f \u062f\u0627\u0631\u062f \u062a\u0627 \u0635\u062d\u0646\u0647 \u0634\u0645\u0627 \u06a9\u0627\u0645\u0644\u0627 \u0648\u0627\u0642\u0639\u06cc \u0634\u0628\u06cc\u0647 \u0633\u0627\u0632\u06cc \u0634\u0648\u062f \u0648\u0644\u06cc \u0627\u06cc\u0646 \u067e\u0644\u0627\u06af\u06cc\u0646 \u0628\u0627 \u062f\u0627\u0631\u0627 \u0628\u0648\u062f\u0646 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647 \u06a9\u0627\u0645\u0644 \u0627\u0632 \u0645\u062a\u0631\u06cc\u0627\u0644 \u0647\u0627&nbsp; \u06a9\u0627\u0631 \u0634\u0645\u0627 \u0631\u0627 \u0628\u0633\u06cc\u0627\u0631 \u0631\u0627\u062d\u062a \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u0648 \u0641\u0642\u0637 \u06a9\u0627\u0641\u06cc\u0633\u062a \u0645\u062a\u0631\u06cc\u0627\u0644 \u0645\u0648\u0631\u062f \u0646\u0638\u0631 \u0631\u0648 \u062f\u0631 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647 \u067e\u0644\u0627\u06af\u06cc\u0646 \u06a9\u0644\u06cc\u06a9 \u06a9\u0646\u06cc\u062f \u0648 \u0645\u062a\u0631\u06cc\u0627\u0644 \u0628\u0633\u06cc\u0627\u0631 \u062d\u0631\u0641\u0647 \u0627\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"text-align: justify\"><img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/archart.ir\/blog\/wp-content\/uploads\/2022\/01\/1578289168_images.jpg\" alt=\"\" title=\"\"><\/span><\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/archart.ir\/blog\/wp-content\/uploads\/2022\/01\/1578290026_93.jpg\" alt=\"\" width=\"391\" height=\"391\" title=\"\"><\/p>\n<p style=\"text-align: justify\"><span style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/archart.ir\/blog\/wp-content\/uploads\/2022\/01\/1578289351_91.jpg\" alt=\"\" width=\"551\" height=\"252\" title=\"\"><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"text-align: justify\"><img decoding=\"async\" class=\"img-fluid\" src=\"https:\/\/archart.ir\/blog\/wp-content\/uploads\/2022\/01\/1578289257_92.jpg\" alt=\"\" title=\"\"><\/span><\/p>\n<p style=\"text-align: justify\">\n<\/p><h1 style=\"text-align: justify\"><span style=\"text-align: justify\">\u0645\u062d\u062a\u0648\u0627:<\/span><\/h1>\n<p dir=\"RTL\" style=\"text-align: justify\"><span style=\"text-align: justify\">\u062a\u06cc\u0645 \u0622\u0645\u0648\u0632\u0634\u06cc <a href=\"https:\/\/archart.ir\/\">\u0622\u0631\u0686 \u0622\u0631\u062a <\/a>\u0645\u0648\u0641\u0642 \u0634\u062f\u0647 \u0627\u0633\u062a \u067e\u0644\u0627\u06af\u06cc\u0646&nbsp; SIGERSHADER \u0631\u0627 \u0628\u0631\u0627\u06cc <strong><a href=\"https:\/\/archart.ir\/Course\/2\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%85%D8%AF%D9%84-%D8%B3%D8%A7%D8%B2%DB%8C-%D9%86%D8%B1%D9%85-%D8%A7%D9%81%D8%B2%D8%A7%D8%B1-%D8%AA%D8%B1%DB%8C-%D8%AF%DB%8C-%D9%85%DA%A9%D8%B3\/\">\u062a\u0631\u06cc \u062f\u06cc \u0645\u06a9\u0633<\/a><\/strong> 2018\u060c 2019 \u0648 2020 \u06a9\u0631\u06a9 \u06a9\u0646\u062f \u0648 \u0645\u06cc \u062e\u0648\u0627\u0647\u06cc\u0645 \u062f\u0631 \u0627\u06cc\u0646 \u0622\u0645\u0648\u0632\u0634 \u0628\u0647 \u0634\u0645\u0627 \u0628\u06af\u0648\u06cc\u06cc\u0645 \u06a9\u0647 \u0686\u06af\u0648\u0646\u0647 \u0627\u06cc\u0646 \u067e\u0644\u0627\u06af\u06cc\u0646 \u0631\u0627 \u0628\u0631\u0627\u06cc <strong><a href=\"https:\/\/archart.ir\/Course\/2\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%85%D8%AF%D9%84-%D8%B3%D8%A7%D8%B2%DB%8C-%D9%86%D8%B1%D9%85-%D8%A7%D9%81%D8%B2%D8%A7%D8%B1-%D8%AA%D8%B1%DB%8C-%D8%AF%DB%8C-%D9%85%DA%A9%D8%B3\/\">\u062a\u0631\u06cc \u062f\u06cc \u0645\u06a9\u0633<\/a><\/strong> 2013 \u062a\u0627 2020 \u0646\u0635\u0628 \u0648 \u06a9\u0631\u06a9 \u06a9\u0646\u06cc\u062f<\/span><\/p>\n<p dir=\"RTL\" style=\"text-align: justify\">\n<\/p><ul>\n<li style=\"text-align: justify\"><span style=\"text-align: justify\">&nbsp;\u062f\u0631 \u0627\u0628\u062a\u062f\u0627 \u0648\u0627\u0631\u062f \u0633\u0627\u06cc\u062a <a href=\"https:\/\/archart.ir\/\">\u0622\u0631\u0686 \u0622\u0631\u062a <\/a>\u0634\u0648\u06cc\u062f \u0648 \u0627\u0632 \u0632\u06cc\u0631 \u0645\u062c\u0645\u0648\u0639\u0647 \u06cc <strong><a href=\"https:\/\/archart.ir\/%D8%A8%D9%84%D8%A7%DA%AF\/\">\u0628\u0644\u0627\u06af<\/a><\/strong> \u06af\u0632\u06cc\u0646\u0647 \u06cc \u067e\u0644\u0627\u06af\u06cc\u0646 \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u0648 \u0631\u0648\u06cc&nbsp; \u0641\u0627\u06cc\u0644 \u062f\u0627\u0646\u0644\u0648\u062f\u06cc \u067e\u0644\u0627\u06af\u06cc\u0646&nbsp;SIGERSHADER \u0631\u0627 \u06a9\u0644\u06cc\u06a9 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"text-align: justify\"><span style=\"text-align: justify\">\u0641\u0627\u06cc\u0644 \u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0642\u0631\u0627\u0631 \u062f\u0627\u062f\u0647 \u0627\u06cc\u0645 \u0631\u0627 \u0637\u0628\u0642 \u0646\u06cc\u0627\u0632 ( \u06a9\u0647 \u062f\u0631 \u0641\u06cc\u0644\u0645 \u0628\u0647 \u0635\u0648\u0631\u062a \u06a9\u0627\u0645\u0644 \u06af\u0641\u062a\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a) \u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"text-align: justify\"><span style=\"text-align: justify\">\u0628\u0639\u062f \u0627\u0632 \u062f\u0627\u0646\u0644\u0648\u062f \u0622\u0646 \u0631\u0627 \u0627\u0632 \u062d\u0627\u0644\u062a \u0641\u0634\u0631\u062f\u0647 \u062e\u0627\u0631\u062c \u06a9\u0646\u06cc\u062f ( \u0628\u0647 \u0639\u0644\u062a \u0633\u0646\u06af\u06cc\u0646\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0632\u0645\u0627\u0646 \u0628\u0628\u0631\u062f \u062a\u0627 \u0627\u0632 \u062d\u0627\u0644\u062a \u0641\u0634\u0631\u062f\u0647 \u062e\u0627\u0631\u062c \u0634\u0648\u062f.)<\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify\">\n<\/p><p style=\"text-align: justify\"><span style=\"text-align: justify\">\u0646\u06a9\u062a\u0647: \u0627\u06af\u0631 \u062f\u0631 \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0641\u0627\u06cc\u0644 \u0631\u0627 \u0627\u0632 \u062d\u0627\u0644\u062a \u0641\u0634\u0631\u062f\u0647 \u062e\u0627\u0631\u062c \u0645\u06cc \u06a9\u0646\u06cc\u062f \u067e\u06cc\u063a\u0627\u0645\u06cc \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0638\u0627\u0647\u0631 \u0634\u062f \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u062f\u0631 \u0642\u0633\u0645\u062a \u067e\u0627\u06cc\u06cc\u0646 \u0647\u0645\u06cc\u0646 \u067e\u0633\u062a \u0633\u0648\u0627\u0644 \u062e\u0648\u062f \u0631\u0627 \u0645\u0637\u0631\u062d \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0645\u0627 \u06cc\u06a9 \u0631\u0648\u0634 \u062f\u06cc\u06af\u0647 \u0627\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u062e\u0627\u0631\u062c \u06a9\u0631\u062f\u0646 \u0641\u0627\u06cc\u0644 \u0627\u0632 \u062d\u0627\u0644\u062a \u0641\u0634\u0631\u062f\u0647 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u06a9\u0627\u0631\u0628\u0631 \u0639\u0632\u06cc\u0632 \u0622\u0645\u0648\u0632\u0634 \u062f\u0647\u06cc\u0645.<\/span><\/p>\n<p style=\"text-align: justify\">\n<\/p><ul>\n<li style=\"text-align: justify\"><span style=\"text-align: justify\">\u0648\u0627\u0631\u062f \u0641\u0627\u06cc\u0644 \u0645\u0648\u0631\u062f \u0646\u0638\u0631 \u0634\u0648\u06cc\u062f \u0648 \u0631\u0648\u06cc \u0641\u0627\u06cc\u0644 \u0646\u0635\u0628 \u0631\u0627\u0633\u062a \u06a9\u0644\u06cc\u06a9 \u06a9\u0631\u062f\u0647 \u0648 \u0633\u067e\u0633 \u0648 \u06af\u0632\u06cc\u0646\u0647 \u06ccrun as administrator &nbsp;\u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"text-align: justify\"><span style=\"text-align: justify\">\u0628\u0639\u062f \u0627\u0632 \u0622\u0646 \u0635\u0641\u062d\u0647 \u0627\u06cc \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0628\u0627\u0632 \u0645\u06cc \u0634\u0648\u062f \u0631\u0648\u06cc \u06af\u0632\u06cc\u0646\u0647 \u06cc NEXT \u06a9\u0644\u06cc\u06a9 \u06a9\u0646\u06cc\u062f. \u0648 \u0633\u067e\u0633 \u062f\u0631 \u067e\u0646\u062c\u0631\u0647 \u06cc \u062c\u062f\u06cc\u062f \u06af\u0632\u06cc\u0646\u0647 I agree \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u062f\u0648\u0628\u0627\u0631\u0647 \u0631\u0648\u06cc next &nbsp;\u06a9\u0644\u06cc\u06a9 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"text-align: justify\"><span style=\"text-align: justify\">\u067e\u0646\u062c\u0631\u0647 \u06cc \u062c\u062f\u06cc\u062f \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0628\u0627\u0632 \u0645\u06cc \u0634\u0648\u062f \u0627\u0632 \u0634\u0645\u0627 \u0645\u06cc \u067e\u0631\u0633\u062f \u0631\u0648\u06cc \u0686\u0647 \u0648\u0631\u0698\u0646 \u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0646\u0635\u0628 \u0634\u0648\u062f.( \u062a\u0648\u062c\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f \u0628\u0631\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0686\u0646\u062f \u0648\u0631\u0698\u0646 \u062d\u062a\u0645\u0627 \u0637\u0628\u0642 \u0646\u06a9\u0627\u062a\u06cc \u06a9\u0647 \u062f\u0631 \u0641\u06cc\u0644\u0645 \u06af\u0641\u062a\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a \u067e\u06cc\u0634 \u0628\u0631\u0648\u06cc\u062f.)<\/span><\/li>\n<li style=\"text-align: justify\"><span style=\"text-align: justify\">&nbsp;next \u0648 install \u0627\u062a\u0646\u062e\u0627\u0628 \u0648 \u0633\u067e\u0633 \u0628\u0639\u062f \u0627\u0632 \u0627\u062a\u0645\u0627\u0645 \u0631\u0648\u06cc finish \u06a9\u0644\u06cc\u06a9 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"text-align: justify\"><span style=\"text-align: justify\">&nbsp;\u0628\u0639\u062f \u0627\u0632 \u0627\u062a\u0645\u0627\u0645 \u0646\u0635\u0628 \u0633\u0631\u0627\u063a \u0646\u0635\u0628 \u06a9\u0631\u06a9 \u062a\u0631\u06cc \u062f\u06cc \u0645\u06a9\u0633 \u0647\u0627\u06cc \u0628\u0627 \u0648\u0631\u0698\u0646 \u0647\u0627\u06cc 2017 \u0628\u0647 \u067e\u0627\u06cc\u06cc\u0646 \u0645\u06cc \u0631\u0648\u06cc\u0645.<\/span><\/li>\n<li style=\"text-align: justify\"><span style=\"text-align: justify\">\u062f\u0631 \u0641\u0627\u06cc\u0644 \u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u0634\u0645\u0627 \u0642\u0631\u0627\u0631 \u062f\u0627\u062f\u0647 \u0627\u06cc\u0645 \u0641\u0627\u06cc\u0644\u06cc \u062f\u0627\u0631\u06cc\u062f \u0628\u0647 \u0646\u0627\u0645 maps\u060c \u0627\u06cc\u0646 \u0641\u0627\u06cc\u0644 \u0631\u0627 cut \u06a9\u0646\u06cc\u062f \u0648 \u0628\u0647 \u062f\u0631\u0627\u06cc\u0648 C \u0628\u0631\u0648\u06cc\u062f \u0648 \u062f\u0631 \u0641\u0648\u0644\u062f\u0631 vmpp max \u0622\u0646 \u0631\u0627 paste \u06a9\u0646\u06cc\u062f.( \u062a\u0648\u062c\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u0641\u0636\u0627\u06cc \u0646\u0633\u0628\u062a\u0627 \u0632\u06cc\u0627\u062f\u06cc \u0631\u0627 \u0645\u06cc \u062e\u0648\u0627\u0647\u062f \u0648 \u0627\u06af\u0631 \u0641\u0636\u0627\u06cc \u0632\u06cc\u0627\u062f\u06cc \u062f\u0631 C \u0646\u062f\u0627\u0634\u062a\u06cc\u062f \u062f\u0631 \u062f\u0631\u0627\u06cc\u0648 \u062f\u06cc\u06af\u0631\u06cc \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u062f \u0648 \u0628\u0639\u062f\u0627 \u0637\u0631\u06cc\u0642\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0622\u0646 \u0631\u0627 \u0622\u0645\u0648\u0632\u0634 \u0645\u06cc \u062f\u0647\u06cc\u0645) <\/span><\/li>\n<li style=\"text-align: justify\"><span style=\"text-align: justify\">\u0641\u0627\u06cc\u0644 \u062f\u0646\u0644\u0648\u062f \u0634\u062f\u0647 \u06cc \u06a9\u0631\u06a9 \u062e\u0648\u062f \u0631\u0627 \u0628\u0627\u0632 \u06a9\u0646\u06cc\u062f&nbsp; (2013 \u0622\u0646 \u0628\u0631\u0627\u06cc \u0648\u0631\u0698\u0646 \u0647\u0627\u06cc 2016-2013 \u0645\u06cc \u0628\u0627\u0634\u062f \u0648 2017\u0622\u0646 \u0628\u0631\u0627\u06cc 2017 \u0628\u0647 \u0628\u0627\u0644\u0627)2013 \u0628\u0627 \u0641\u0631\u0645\u062a dll \u0631\u0627 \u0627\u0646\u062a\u062e\u0627\u0628 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"text-align: justify\"><span style=\"text-align: justify\">\u0628\u0647 \u0641\u0648\u0644\u062f\u0631\u06cc \u0628\u0631\u0648\u06cc\u062f \u06a9\u0647 \u0641\u0627\u06cc\u0644 \u062a\u0631\u06cc \u062f\u06cc \u0645\u06a9\u0633 \u0646\u0635\u0628 \u0627\u0633\u062a(\u062f\u0631 \u0642\u0633\u0645\u062a \u0646\u0648\u0627\u0631 start \u0622\u0646 \u0631\u0627 \u067e\u06cc\u062f\u0627 \u06a9\u0646\u06cc\u062f \u0633\u067e\u0633 \u0631\u0627\u0633\u062a \u06a9\u0644\u06cc\u06a9 \u0648 \u06af\u0632\u06cc\u0646\u0647 \u06cc open file location \u06a9\u0644\u06cc\u06a9 \u0645\u06cc \u06a9\u0646\u06cc\u062f \u0631\u0648\u06cc \u0622\u06cc\u06a9\u0648\u0646 \u0628\u0627\u0632 \u0634\u062f\u0647 \u062f\u0648\u0628\u0627\u0631\u0647 \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0631\u0627 \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc \u062f\u0647\u06cc\u062f.)\u0648 \u062f\u0631 \u062f\u0627\u062e\u0644 \u0641\u0648\u0644\u062f\u0631 bin \u0648 assemblies \u0622\u0646 \u0631\u0627 paste \u0648 \u062c\u0627\u06cc\u06af\u0632\u06cc\u0646 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"text-align: justify\"><span style=\"text-align: justify\">&nbsp;\u062f\u0631 \u0627\u06cc\u0646 \u0645\u0631\u062d\u0644\u0647 \u0641\u0627\u06cc\u0644 \u0634\u0645\u0627&nbsp; \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646 \u0648\u0631\u0698\u0646 \u0646\u0635\u0628 \u0648 \u06a9\u0631\u06a9 \u0634\u062f\u0647 \u0627\u0633\u062a.<\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify\">\n<\/p><ul>\n<li>\n<h2 style=\"text-align: justify\"><span style=\"text-align: justify\">\u0627\u0645\u0627 \u0686\u06af\u0648\u0646\u0647 \u067e\u0644\u0627\u06af\u0646 SIGERSHADER \u0631\u0627 \u0628\u0631\u0627\u06cc \u0648\u0631\u0698\u0646 \u0647\u0627\u06cc \u0628\u0627\u0644\u0627 \u06a9\u0631\u06a9 \u06a9\u0646\u06cc\u0645.\u061f\u061f\u061f\u061f<\/span><\/h2>\n<\/li>\n<\/ul>\n<p style=\"text-align: justify\">\n<\/p><ul>\n<li style=\"text-align: justify\"><span style=\"text-align: justify\">\u0628\u0627\u06af\u0630\u0631\u0627\u0646\u062f\u0646 \u0645\u0631\u0627\u062d\u0644 \u0628\u0627\u0644\u0627 \u062f\u0631 \u0646\u0635\u0628\u060c \u06a9\u0631\u06a9 \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0648\u0631\u0698\u0646 \u0645\u0648\u0631\u062f \u0646\u0638\u0631 \u0631\u0627 \u062f\u0627\u0646\u0644\u0648\u062f \u06a9\u0646\u06cc\u062f. \u0628\u0639\u062f \u0627\u0632 \u0628\u0627\u0632 \u06a9\u0631\u062f\u0646 \u0622\u0646 \u0627\u0632 \u062d\u0627\u0644\u062a \u0641\u0634\u0631\u062f\u0647 \u062a\u0645\u0627\u0645 \u0641\u0627\u06cc\u0644 \u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0631 \u0622\u0646 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0647 \u0627\u0646\u062f \u0631\u0627 \u06a9\u067e\u06cc \u06a9\u0646\u06cc\u062f \u0648 \u0633\u067e\u0633 \u0628\u0647 \u0645\u062d\u0644 \u0646\u0635\u0628 \u062a\u0631\u06cc \u062f\u06cc \u0645\u06a9\u0633 2020 \u0628\u0631\u0648\u06cc\u062f \u0648 \u0622\u0646 \u0647\u0627 \u0631\u0627 paste \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"text-align: justify\"><span style=\"text-align: justify\">\u062a\u0648\u062c\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u0641\u0627\u06cc\u0644 maps \u0647\u0645 \u0628\u0647 \u0637\u0631\u06cc\u0642\u0647 \u06cc \u0628\u0627\u0644\u0627 \u062f\u0631 \u062c\u0627\u06cc \u062e\u0648\u062f\u0634 \u0642\u0631\u0627\u0631 \u062f\u0627\u062f\u0647 \u0634\u0648\u062f.<\/span><\/li>\n<li style=\"text-align: justify\"><span style=\"text-align: justify\">\u0647\u0645 \u0627\u06a9\u0646\u0648\u0646 \u067e\u0644\u0627\u06af\u06cc\u0646 SIGERSHADER \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u0642\u0627\u0628\u0644 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0633\u062a.<\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify\">\n<\/p><h1 style=\"text-align: justify\"><span style=\"text-align: justify\">\u062a\u0648\u0635\u06cc\u0647 :<\/span><\/h1>\n<p style=\"text-align: justify\"><span style=\"text-align: justify\">\u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u067e\u0631\u062a\u0627\u0644 \u0622\u0645\u0648\u0632\u0634\u06cc<a href=\"https:\/\/www.archart.ir\/\">&nbsp;\u0622\u0631\u0686 \u0622\u0631\u062a<\/a>&nbsp; \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u062a\u0645\u0627\u0645\u06cc&nbsp;\u0646\u0631\u0645 \u0627\u0641\u0632\u0627\u0631 \u0647\u0627&nbsp;\u0648&nbsp;\u067e\u0644\u0627\u06af\u06cc\u0646&nbsp;\u0647\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u0631\u0648\u0632 \u06a9\u0646\u06cc\u062f. \u0641\u0631\u0627\u0645\u0648\u0634 \u0646\u06a9\u0646\u06cc\u062f \u0647\u0645\u0632\u0645\u0627\u0646 \u0628\u0627&nbsp;update&nbsp;\u062c\u062f\u06cc\u062f \u0647\u0631 \u0646\u0631\u0645 \u0627\u0641\u0632\u0627\u0631 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f&nbsp;<a href=\"https:\/\/www.archart.ir\/%D8%AF%D9%88%D8%B1%D9%87-%D9%87%D8%A7\/\">\u0648\u06cc\u062f\u06cc\u0648 \u0647\u0627\u06cc \u0622\u0645\u0648\u0632\u0634\u06cc<\/a>&nbsp;\u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0622\u0646 \u0646\u0631\u0645 \u0627\u0641\u0632\u0627\u0631 \u0631\u0627 \u0645\u0634\u0627\u0647\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/span><\/p>\n<p style=\"text-align: justify\">\n<\/p><h2><strong><span style=\"color: #e74c3c\">\u062a\u0648\u062c\u0647 \u062a\u0648\u062c\u0647 !!! \u0622\u062e\u0631\u06cc\u0646 \u0646\u0633\u062e\u0647 \u06cc \u0627\u06cc\u0646 \u067e\u0644\u0627\u06af\u06cc\u0646 \u0645\u0646\u062a\u0634\u0631 \u0634\u062f<\/span><\/strong><\/h2>\n<h2><a href=\"https:\/\/archart.ir\/PostByTag\/303\/SIGERSHADERS\/\"><strong>\u0628\u0631\u0627\u06cc \u062f\u0627\u0646\u0644\u0648\u062f \u0627\u062e\u0631\u06cc\u0646 \u0646\u0633\u062e\u0647 \u0627\u06cc\u0646 \u067e\u0644\u0627\u06af\u06cc\u0646 \u0631\u0648\u06cc \u0627\u06cc\u0646 \u0644\u06cc\u0646\u06a9 \u06a9\u0644\u06cc\u06a9 \u0641\u0631\u0645\u0627\u06cc\u06cc\u062f.<\/strong><\/a><\/h2>\n<h1 style=\"text-align: justify\">\u0645\u0648\u0627\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 :<\/h1>\n<p style=\"text-align: justify\">\u0645\u062c\u0645\u0648\u0639\u0647 \u0645\u062a\u0631\u06cc\u0627\u0644 \u0647\u0627\u06cc \u0622\u0645\u0627\u062f\u0647 <a href=\"https:\/\/archart.ir\/Course\/3\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%BE%D9%84%D8%A7%DA%AF%DB%8C%D9%86-Vray-\/\">VRay<\/a> \u0645\u0648\u062c\u0628 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0633\u0631\u0639\u062a&nbsp;\u067e\u0631\u0648\u0698\u0647 \u0647\u0627\u06cc \u0633\u0647 \u0628\u0639\u062f\u06cc \u0634\u0645\u0627 \u0645\u06cc \u0634\u0648\u062f. \u0627\u06cc\u0646 \u067e\u0644\u0627\u06af\u06cc\u0646 \u062a\u0645\u0627\u0645\u06cc \u0645\u062a\u0631\u06cc\u0627\u0644 \u0647\u0627\u06cc \u067e\u0631\u06a9\u0627\u0631\u0628\u0631\u062f \u0631\u0627 \u062f\u0631 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647 \u062e\u0648\u062f \u0642\u0631\u0627\u0631 \u062f\u0627\u062f\u0647 \u0628\u0647 \u0647\u0645\u06cc\u0646 \u0633\u0628\u0628 \u062a\u0642\u0631\u06cc\u0628\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646 \u06af\u0641\u062a \u062a\u0645\u0627\u0645\u06cc \u06a9\u0627\u0631\u0628\u0631\u0627\u0646 \u0646\u0631\u0645 \u0627\u0641\u0632\u0627\u0631&nbsp;<a href=\"https:\/\/www.archart.ir\/Course\/2\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%85%D8%AF%D9%84-%D8%B3%D8%A7%D8%B2%DB%8C-%D9%86%D8%B1%D9%85-%D8%A7%D9%81%D8%B2%D8%A7%D8%B1-%D8%AA%D8%B1%DB%8C-%D8%AF%DB%8C-%D9%85%DA%A9%D8%B3\/\">\u062a\u0631\u06cc \u062f\u06cc \u0645\u06a9\u0633<\/a>&nbsp;\u0648 \u067e\u0644\u0627\u06af\u06cc\u0646&nbsp;<a href=\"https:\/\/www.archart.ir\/Course\/3\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%BE%D9%84%D8%A7%DA%AF%DB%8C%D9%86-Vray-\/\">\u0648\u06cc \u0631\u06cc<\/a>&nbsp;\u0627\u06cc\u0646 \u067e\u0644\u0627\u06af\u06cc\u0646 \u0631\u0627 \u0645\u0648\u0631\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0641\u0639\u0627\u0644\u06cc\u062a \u0647\u0627\u06cc \u062e\u0648\u062f \u0642\u0631\u0627\u0631 \u0645\u06cc \u062f\u0647\u0646\u062f.<\/p>\n<hr>\n<p style=\"text-align: justify\">\n<\/p><div id=\"11751477725\" style=\"text-align: justify\"><\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00a0SIGERSHADER (\u0633\u06cc\u062c\u0631\u0634\u06cc\u062f\u0631) \u06cc\u06a9\u00a0\u067e\u0644\u0627\u06af\u06cc\u0646 \u062a\u0631\u06cc \u062f\u06cc \u0645\u06a9\u0633\u00a0\u0628\u0631\u0627\u06cc \u0648\u0631\u0698\u0646 2013 \u062a\u0627 2020 \u0645\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u0634\u0627\u0645\u0644 \u0627\u0646\u0648\u0627\u0639 \u0645\u062a\u0631\u06cc\u0627\u0644 \u0647\u0627\u06cc \u0622\u0645\u0627\u062f\u0647 \u0628\u0631\u0627\u06cc\u00a0V-Ray \u0645\u06cc \u0628\u0627\u0634\u062f,\u062f\u0631 \u062d\u0627\u0644\u062a \u0639\u0627\u062f\u06cc \u0633\u0627\u062e\u062a \u0645\u062a\u0631\u06cc\u0627\u0644 \u0647\u0627\u06cc \u062d\u0631\u0641\u0647 \u0627\u06cc \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0632\u0645\u0627\u0646 \u0648 \u062a\u062c\u0631\u0628\u0647 \u062e\u06cc\u0644\u06cc \u0632\u06cc\u0627\u062f \u062f\u0627\u0631\u062f \u062a\u0627 \u0635\u062d\u0646\u0647 \u0634\u0645\u0627 \u06a9\u0627\u0645\u0644\u0627 \u0648\u0627\u0642\u0639\u06cc \u0634\u0628\u06cc\u0647 \u0633\u0627\u0632\u06cc \u0634\u0648\u062f \u0648\u0644\u06cc \u0627\u06cc\u0646 \u067e\u0644\u0627\u06af\u06cc\u0646 \u0628\u0627 \u062f\u0627\u0631\u0627 \u0628\u0648\u062f\u0646 \u06a9\u062a\u0627\u0628\u062e\u0627\u0646\u0647 \u06a9\u0627\u0645\u0644 \u0627\u0632 \u0645\u062a\u0631\u06cc\u0627\u0644 \u0647\u0627\u00a0 [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":1614,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,2],"tags":[195,1085,1086,1083,1084],"class_list":["post-1609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category---installation","category-2","tag-sigershaders","tag-1085","tag---siger-shader","tag---sigershaders","tag-1084"],"amp_enabled":false,"acf":[],"_links":{"self":[{"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/posts\/1609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/comments?post=1609"}],"version-history":[{"count":0,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/posts\/1609\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/media\/1614"}],"wp:attachment":[{"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/media?parent=1609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/categories?post=1609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/tags?post=1609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}