<br />
<b>Warning</b>:  file_exists(): open_basedir restriction in effect. File(/home/archart/domains/archart.ir/public_html/blog/wp-content/plugins/wp-rocket/) is not within the allowed path(s): (/home/h379408/:/tmp:/var/tmp:/opt/alt/php81/usr/share/pear/:/dev/urandom:/usr/local/lib/php/:/usr/local/php81/lib/php/) in <b>/home/h379408/domains/archart.ir/public_html/blog/wp-content/advanced-cache.php</b> on line <b>17</b><br />
{"id":2172,"date":"2021-09-01T11:55:26","date_gmt":"2021-09-01T07:25:26","guid":{"rendered":"https:\/\/archart.ir\/blog\/%d9%85%db%8c%d8%af%d9%88%d9%86%d8%b3%d8%aa%db%8c-%d9%85%db%8c-%d8%aa%d9%88%d9%86%db%8c-%d8%a8%d8%af%d9%88%d9%86-%da%af%d8%b1%d9%81%d8%aa%d9%86-%d8%b1%d9%86%d8%af%d8%b1-%d9%85%d8%ac%d8%af%d8%af-%d8%b4\/"},"modified":"2022-01-24T08:31:56","modified_gmt":"2022-01-24T05:01:56","slug":"%d9%85%db%8c%d8%af%d9%88%d9%86%d8%b3%d8%aa%db%8c-%d9%85%db%8c-%d8%aa%d9%88%d9%86%db%8c-%d8%a8%d8%af%d9%88%d9%86-%da%af%d8%b1%d9%81%d8%aa%d9%86-%d8%b1%d9%86%d8%af%d8%b1-%d9%85%d8%ac%d8%af%d8%af-%d8%b4","status":"publish","type":"post","link":"https:\/\/archart.ir\/blog\/%d9%85%db%8c%d8%af%d9%88%d9%86%d8%b3%d8%aa%db%8c-%d9%85%db%8c-%d8%aa%d9%88%d9%86%db%8c-%d8%a8%d8%af%d9%88%d9%86-%da%af%d8%b1%d9%81%d8%aa%d9%86-%d8%b1%d9%86%d8%af%d8%b1-%d9%85%d8%ac%d8%af%d8%af-%d8%b4\/","title":{"rendered":"\u0645\u06cc\u062f\u0648\u0646\u0633\u062a\u06cc \u0645\u06cc \u062a\u0648\u0646\u06cc \u0628\u062f\u0648\u0646 \u06af\u0631\u0641\u062a\u0646 \u0631\u0646\u062f\u0631 \u0645\u062c\u062f\u062f \u0634\u062f\u062a \u0648 \u0631\u0646\u06af \u0646\u0648\u0631 \u0631\u0648 \u062a\u063a\u06cc\u06cc\u0631 \u0628\u062f\u06cc\u0646 \u061f\u061f\u061f"},"content":{"rendered":"\n<div id=\"44193742168\"><script type=\"text\/JavaScript\" src=\"https:\/\/www.aparat.com\/embed\/exuD7?data[rnddiv]=44193742168&amp;data[responsive]=yes\"><\/script><\/div>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n<div class=\"col-12 col-lg-9 mt-3\">\n<div class=\"dirRtl TAR text-justify\" data-aos=\"fade-up\">\n<div id=\"61933283082\"><\/div>\n<hr>\n<p>\u0627\u06af\u0647 \u062f\u0646\u0628\u0627\u0644 \u0627\u06cc\u0646 \u0647\u0633\u062a\u06cc \u06a9\u0647 \u0628\u062f\u0648\u0646 \u06af\u0631\u0641\u062a\u0646 \u0631\u0646\u062f\u0631 \u0645\u062c\u062f\u062f \u0628\u062a\u0648\u0646\u06cc \u0634\u062f\u062a \u0648 \u0631\u0646\u06af \u0646\u0648\u0631\u062a \u0631\u0648 \u062a\u063a\u06cc\u06cc\u0631 \u0628\u062f\u06cc \u062d\u062a\u0645\u0627 \u0628\u0647\u062a \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc \u06a9\u0646\u0645 \u0627\u06cc\u0646 \u0648\u06cc\u062f\u0626\u0648 \u0622\u0645\u0648\u0632\u0634\u06cc \u0631\u0627 \u062a\u0627 \u0627\u0646\u062a\u0647\u0627 \u062f\u0646\u0628\u0627\u0644 \u06a9\u0646\u06cc\u062f\u270c\u261d\u261d\u261d<\/p>\n<p>\u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0648\u0634 \u0647\u0627\u06cc \u062e\u06cc\u0644\u06cc \u062e\u0648\u0628 \u0648 \u062f\u0648\u0633\u062a \u062f\u0627\u0634\u062a\u0646\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u0648\u062a\u0648\u0631 brute force \u0648 lightmix \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0622\u0645\u0648\u0632\u0634 \u0628\u0647\u0634 \u0627\u0634\u0627\u0631\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a&#8230;<\/p>\n<p>\u0627\u06af\u0631 \u062f\u0648\u0633\u062a \u062f\u0627\u0631\u06cc\u062f \u06a9\u0647 \u0644\u0627\u06cc\u062a \u0645\u06cc\u06a9\u0633 \u0648 \u062a\u06a9\u0646\u06cc\u06a9 \u0647\u0627\u06cc \u0646\u0648\u0631 \u067e\u0631\u062f\u0627\u0632\u06cc \u0631\u0627 \u0628\u0647 \u0635\u0648\u0631\u062a \u06a9\u0627\u0645\u0644 \u06cc\u0627\u062f \u0628\u06af\u06cc\u0631\u06cc\u062f \u0628\u0647\u062a\u0648\u0646 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc \u06a9\u0646\u0645 \u06a9\u0647 \u062d\u062a\u0645\u0627 \u0627\u0632 \u062f\u0648\u0631\u0647 \u06cc <a href=\"https:\/\/archart.ir\/Course\/3\/%D9%88%DB%8C%D8%B1%DB%8C-%D8%A2%D9%88%D8%A7%D9%86%DA%AF%D8%A7%D8%B1%D8%AF-(%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%BE%D9%84%D8%A7%DA%AF%DB%8C%D9%86-Vray)\/\"><strong>\u0648\u06cc \u0631\u06cc \u0622\u0648\u0627\u0646\u06af\u0627\u0631\u062f<\/strong><\/a> \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f<\/p>\n<p><a href=\"https:\/\/archart.ir\/Course\/3\/%D9%88%DB%8C%D8%B1%DB%8C-%D8%A2%D9%88%D8%A7%D9%86%DA%AF%D8%A7%D8%B1%D8%AF-(%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%BE%D9%84%D8%A7%DA%AF%DB%8C%D9%86-Vray)\/\"><strong>\u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u062f\u0648\u0633\u062a \u062f\u0627\u0631\u06cc\u062f \u0628\u062e\u0634\u06cc \u0627\u0632 \u062c\u0644\u0633\u0647 11 \u062f\u0648\u0631\u0647 \u06cc \u0648\u06cc \u0631\u06cc \u0622\u0648\u0627\u0646\u06af\u0627\u0631\u062f \u06a9\u0647&nbsp; \u0644\u0627\u06cc\u062a \u0645\u06cc\u06a9\u0633 \u0631\u0627 \u0622\u0645\u0648\u0632\u0634 \u062f\u0627\u062f\u0647 \u0627\u06cc\u0645&nbsp; \u0631\u0648 \u0628\u0628\u06cc\u0646\u06cc\u062f \u0631\u0648\u06cc \u0647\u0645\u06cc\u0646 \u0644\u06cc\u0646\u06a9 \u06a9\u0644\u06cc\u06a9 \u06a9\u0646\u06cc\u062f.<\/strong><\/a><\/p>\n<h2>\u0686\u0631\u0627 light mix \u06a9\u0627\u0631 \u0646\u0645\u06cc \u06a9\u0646\u062f \u061f\u061f\u061f<\/h2>\n<p>\u062c\u0648\u0627\u0628 \u0628\u0647 \u0627\u06cc\u0646 \u0633\u0648\u0627\u0644 \u0631\u0627 \u062f\u0631 \u0648\u06cc\u062f\u0626\u0648 \u0628\u0627\u0644\u0627 \u0628\u0647 \u0635\u0648\u0631\u062a \u06a9\u0627\u0645\u0644 \u0622\u0645\u0648\u0632\u0634 \u062f\u0627\u062f\u0647 \u0627\u06cc\u0645 \u0648 \u0644\u06cc\u0644 \u0622\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 <strong><a href=\"http:\/\/archart.ir\/Course\/3\/%D9%88%DB%8C%D8%B1%DB%8C-%D8%A2%D9%88%D8%A7%D9%86%DA%AF%D8%A7%D8%B1%D8%AF-(%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%BE%D9%84%D8%A7%DA%AF%DB%8C%D9%86-Vray)\/\">\u0645\u0648\u062a\u0648\u0631 \u0647\u0627\u06cc \u0631\u0646\u062f\u0631<\/a><\/strong> \u0646\u0627 \u0635\u062d\u06cc\u062d \u062f\u0631 \u062a\u0646\u0638\u06cc\u0645\u0627\u062a gi \u0645\u06cc \u0628\u0627\u0634\u062f.<\/p>\n<h2>\u0622\u06cc\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u0645&nbsp; \u0644\u0627\u06cc\u062a \u0645\u06cc\u06a9\u0633 \u0631\u0627 \u0628\u0627 \u0645\u0648\u062a\u0648\u0631 \u0631\u0646\u062f\u0631irradiance map \u0641\u0639\u0627\u0644 \u06a9\u0646\u06cc\u0645 \u061f\u061f\u061f<\/h2>\n<p>\u0642\u0637\u0639\u0627 \u0627\u0645\u06a9\u0627\u0646 \u0641\u0639\u0627\u0644 \u06a9\u0631\u062f\u0646 \u0644\u0627\u06cc\u062a \u0645\u06cc\u06a9\u0633 \u0628\u0631\u0627\u06cc \u0645\u0648\u062a\u0648\u0631\u06cc \u0628\u0647 \u063a\u06cc\u0631 \u0627\u0632 brute force \u0648\u062c\u0648\u062f \u0646\u062f\u0627\u0631\u062f \u062a\u0627 \u0627\u0645\u0631\u0648\u0632 \u0634\u0627\u06cc\u062f \u062f\u0631 \u0622\u06cc\u0646\u062f\u0647 \u0627\u06cc\u0646 \u0627\u0645\u06a9\u0627\u0646 \u0641\u0631\u0627\u0647\u0645 \u0622\u06cc\u062f.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0627\u06af\u0647 \u062f\u0646\u0628\u0627\u0644 \u0627\u06cc\u0646 \u0647\u0633\u062a\u06cc \u06a9\u0647 \u0628\u062f\u0648\u0646 \u06af\u0631\u0641\u062a\u0646 \u0631\u0646\u062f\u0631 \u0645\u062c\u062f\u062f \u0628\u062a\u0648\u0646\u06cc \u0634\u062f\u062a \u0648 \u0631\u0646\u06af \u0646\u0648\u0631\u062a \u0631\u0648 \u062a\u063a\u06cc\u06cc\u0631 \u0628\u062f\u06cc \u062d\u062a\u0645\u0627 \u0628\u0647\u062a \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc \u06a9\u0646\u0645 \u0627\u06cc\u0646 \u0648\u06cc\u062f\u0626\u0648 \u0622\u0645\u0648\u0632\u0634\u06cc \u0631\u0627 \u062a\u0627 \u0627\u0646\u062a\u0647\u0627 \u062f\u0646\u0628\u0627\u0644 \u06a9\u0646\u06cc\u062f\u270c\u261d\u261d\u261d \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0648\u0634 \u0647\u0627\u06cc \u062e\u06cc\u0644\u06cc \u062e\u0648\u0628 \u0648 \u062f\u0648\u0633\u062a \u062f\u0627\u0634\u062a\u0646\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u0648\u062a\u0648\u0631 brute force \u0648 lightmix \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0622\u0645\u0648\u0632\u0634 \u0628\u0647\u0634 \u0627\u0634\u0627\u0631\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a&#8230; [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":2173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,4],"tags":[1902,1903,1907,1904,1906,1631,1392,1905,1901],"class_list":["post-2172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2","category---vray","tag-light-mix","tag-lightmix","tag--light-mix","tag--lightmix","tag-1906","tag-1631","tag-1392","tag-1905","tag-1901"],"amp_enabled":false,"acf":[],"_links":{"self":[{"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/posts\/2172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/comments?post=2172"}],"version-history":[{"count":0,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/posts\/2172\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/media\/2173"}],"wp:attachment":[{"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/media?parent=2172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/categories?post=2172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/tags?post=2172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}