<br />
<b>Warning</b>:  file_exists(): open_basedir restriction in effect. File(/home/archart/domains/archart.ir/public_html/blog/wp-content/plugins/wp-rocket/) is not within the allowed path(s): (/home/h379408/:/tmp:/var/tmp:/opt/alt/php81/usr/share/pear/:/dev/urandom:/usr/local/lib/php/:/usr/local/php81/lib/php/) in <b>/home/h379408/domains/archart.ir/public_html/blog/wp-content/advanced-cache.php</b> on line <b>17</b><br />
{"id":3065,"date":"2022-04-17T21:06:23","date_gmt":"2022-04-17T16:36:23","guid":{"rendered":"https:\/\/archart.ir\/blog\/?p=3065"},"modified":"2022-04-18T11:28:32","modified_gmt":"2022-04-18T06:58:32","slug":"%d9%85%d8%af%d9%84-%d8%b3%d8%a7%d8%b2%db%8c-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%af%d8%b1-3ds-max","status":"publish","type":"post","link":"https:\/\/archart.ir\/blog\/%d9%85%d8%af%d9%84-%d8%b3%d8%a7%d8%b2%db%8c-%d9%84%d9%88%d8%b3%d8%aa%d8%b1-%d8%af%d8%b1-3ds-max\/","title":{"rendered":"\u0645\u062f\u0644 \u0633\u0627\u0632\u06cc \u0644\u0648\u0633\u062a\u0631 \u062f\u0631 3ds max"},"content":{"rendered":"\n<div id=\"91570215432\"><script type=\"text\/JavaScript\" src=\"https:\/\/www.aparat.com\/embed\/0oHqK?data[rnddiv]=91570215432&amp;data[responsive]=yes\"><\/script><\/div>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<p>\u062f\u0631 \u0627\u06cc\u0646 \u0648\u06cc\u062f\u06cc\u0648 \u0645\u0627 \u0628\u0647 \u0634\u0645\u0627 <a href=\"https:\/\/archart.ir\/Course\/2\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%85%D8%AF%D9%84-%D8%B3%D8%A7%D8%B2%DB%8C-%D9%86%D8%B1%D9%85-%D8%A7%D9%81%D8%B2%D8%A7%D8%B1-%D8%AA%D8%B1%DB%8C-%D8%AF%DB%8C-%D9%85%DA%A9%D8%B3\/\">\u0645\u062f\u0644 \u0633\u0627\u0632\u06cc<\/a> \u0644\u0648\u0633\u062a\u0631 \u062f\u0631 <a href=\"https:\/\/archart.ir\/Course\/2\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%85%D8%AF%D9%84-%D8%B3%D8%A7%D8%B2%DB%8C-%D9%86%D8%B1%D9%85-%D8%A7%D9%81%D8%B2%D8%A7%D8%B1-%D8%AA%D8%B1%DB%8C-%D8%AF%DB%8C-%D9%85%DA%A9%D8%B3\/\">\u0646\u0631\u0645 \u0627\u0641\u0632\u0627\u0631 \u062a\u0631\u06cc \u062f\u06cc \u0645\u06a9\u0633<\/a> \u0631\u0627 \u0627\u0645\u0648\u0632\u0634 \u0645\u06cc\u062f\u0647\u06cc\u0645. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u0645\u062f\u0644 \u0633\u0627\u0632\u06cc \u0644\u0648\u0633\u062a\u0631 \u0627\u0632 \u0686\u0647 \u0631\u0648\u0634 \u061f<\/h2>\n\n\n\n<p>\u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0648\u0634 \u0647\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u062f\u0647 \u062f\u0631 \u0627\u06cc\u0646 <a href=\"https:\/\/archart.ir\/Course\/2\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%85%D8%AF%D9%84-%D8%B3%D8%A7%D8%B2%DB%8C-%D9%86%D8%B1%D9%85-%D8%A7%D9%81%D8%B2%D8%A7%D8%B1-%D8%AA%D8%B1%DB%8C-%D8%AF%DB%8C-%D9%85%DA%A9%D8%B3\/\">\u0645\u062f\u0644 \u0633\u0627\u0632\u06cc<\/a> \u060c <a href=\"https:\/\/archart.ir\/Course\/2\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%85%D8%AF%D9%84-%D8%B3%D8%A7%D8%B2%DB%8C-%D9%86%D8%B1%D9%85-%D8%A7%D9%81%D8%B2%D8%A7%D8%B1-%D8%AA%D8%B1%DB%8C-%D8%AF%DB%8C-%D9%85%DA%A9%D8%B3\/\">\u0645\u062f\u0644 \u0633\u0627\u0632\u06cc<\/a> \u067e\u0627\u0631\u0627\u0645\u062a\u0631\u06cc\u06a9 \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0648\u06cc\u062f\u06cc\u0648 \u0628\u0627\u0644\u0627 \u0645\u0627 \u0628\u0647 \u06a9\u0645\u06a9 \u0622\u0646 \u0644\u0648\u0633\u062a\u0631 \u0631\u0627 <a href=\"https:\/\/archart.ir\/Course\/2\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%85%D8%AF%D9%84-%D8%B3%D8%A7%D8%B2%DB%8C-%D9%86%D8%B1%D9%85-%D8%A7%D9%81%D8%B2%D8%A7%D8%B1-%D8%AA%D8%B1%DB%8C-%D8%AF%DB%8C-%D9%85%DA%A9%D8%B3\/\">\u0645\u062f\u0644 \u0633\u0627\u0632\u06cc<\/a> \u06a9\u0631\u062f\u06cc\u0645 <\/p>\n\n\n\n<p>\u062d\u062a\u0645\u0627 \u0627\u06cc\u0646 \u0648\u06cc\u062f\u06cc\u0648 \u0631\u0627 \u062a\u0627 \u0627\u0646\u062a\u0647\u0627 \u0628\u0628\u06cc\u0646\u062f\u06cc\u062f \u0648 \u0646\u0638\u0631\u0627\u062a \u0648 \u0633\u0648\u0627\u0644\u0627\u062a \u062e\u0648\u062f\u062a\u0648\u0646 \u0631\u0648 \u0628\u0627 \u0645\u0627 \u062f\u0631 \u0645\u06cc\u0648\u0646 \u0628\u0632\u0627\u0631\u06cc\u062f.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u062f\u0631 \u0627\u06cc\u0646 \u0648\u06cc\u062f\u06cc\u0648 \u0645\u0627 \u0628\u0647 \u0634\u0645\u0627 \u0645\u062f\u0644 \u0633\u0627\u0632\u06cc \u0644\u0648\u0633\u062a\u0631 \u062f\u0631 \u0646\u0631\u0645 \u0627\u0641\u0632\u0627\u0631 \u062a\u0631\u06cc \u062f\u06cc \u0645\u06a9\u0633 \u0631\u0627 \u0627\u0645\u0648\u0632\u0634 \u0645\u06cc\u062f\u0647\u06cc\u0645. \u0645\u062f\u0644 \u0633\u0627\u0632\u06cc \u0644\u0648\u0633\u062a\u0631 \u0627\u0632 \u0686\u0647 \u0631\u0648\u0634 \u061f&#8230;<\/p>\n","protected":false},"author":2,"featured_media":3066,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,3],"tags":[3232,3231],"class_list":["post-3065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2","category---3ds-max","tag-----3ds-max","tag-3231"],"amp_enabled":false,"acf":[],"_links":{"self":[{"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/posts\/3065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/comments?post=3065"}],"version-history":[{"count":0,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/posts\/3065\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/media\/3066"}],"wp:attachment":[{"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/media?parent=3065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/categories?post=3065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/tags?post=3065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}