<br />
<b>Warning</b>:  file_exists(): open_basedir restriction in effect. File(/home/archart/domains/archart.ir/public_html/blog/wp-content/plugins/wp-rocket/) is not within the allowed path(s): (/home/h379408/:/tmp:/var/tmp:/opt/alt/php81/usr/share/pear/:/dev/urandom:/usr/local/lib/php/:/usr/local/php81/lib/php/) in <b>/home/h379408/domains/archart.ir/public_html/blog/wp-content/advanced-cache.php</b> on line <b>17</b><br />
{"id":3152,"date":"2022-06-14T13:23:34","date_gmt":"2022-06-14T08:53:34","guid":{"rendered":"https:\/\/archart.ir\/blog\/?p=3152"},"modified":"2022-06-14T12:26:11","modified_gmt":"2022-06-14T07:56:11","slug":"2-%d8%b1%d9%88%d8%b4-%d8%b3%d8%a7%d8%ae%d8%aa-%d8%a8%d9%84%d8%a7%da%a9-%d8%af%d8%a7%db%8c%d9%86%d8%a7%d9%85%db%8c%da%a9-%d8%a7%d8%aa%d9%88%da%a9%d8%af-2023","status":"publish","type":"post","link":"https:\/\/archart.ir\/blog\/2-%d8%b1%d9%88%d8%b4-%d8%b3%d8%a7%d8%ae%d8%aa-%d8%a8%d9%84%d8%a7%da%a9-%d8%af%d8%a7%db%8c%d9%86%d8%a7%d9%85%db%8c%da%a9-%d8%a7%d8%aa%d9%88%da%a9%d8%af-2023\/","title":{"rendered":"2 \u0631\u0648\u0634 \u0633\u0627\u062e\u062a \u0628\u0644\u0627\u06a9 \u062f\u0627\u06cc\u0646\u0627\u0645\u06cc\u06a9 \u0627\u062a\u0648\u06a9\u062f 2023"},"content":{"rendered":"\n<p>\u06cc\u06a9\u06cc \u0627\u0632 \u0648\u06cc\u0698\u06af\u06cc \u0647\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u062f\u0631 <a href=\"https:\/\/archart.ir\/Course\/1\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%86%D8%B1%D9%85-%D8%A7%D9%81%D8%B2%D8%A7%D8%B1-%D8%A7%D8%AA%D9%88%DA%A9%D8%AF-%D8%AF%D9%88-%D8%A8%D8%B9%D8%AF%DB%8C\/\">\u0627\u062a\u0648\u06a9\u062f <\/a>, \u0633\u0627\u062e\u062a \u062f\u0627\u06cc\u0646\u0627\u0645\u06cc\u06a9 \u0628\u0644\u0627\u06a9 \u0627\u0633\u062a \u06a9\u0647 \u062a\u0648\u06cc \u0627\u06cc\u0646 \u0622\u0645\u0648\u0632\u0634 \u0628\u0647 \u0634\u0645\u0627 \u06cc\u0627\u062f \u0645\u06cc \u062f\u0647\u06cc\u0645 \u0686\u0637\u0648\u0631 \u0628\u0644\u0627\u06a9 \u0647\u0627\u06cc \u062f\u0627\u06cc\u0646\u0627\u0645\u06cc\u06a9 \u0631\u0627 \u062e\u0644\u0642 \u06a9\u0646\u06cc\u062f.<\/p>\n\n\n\n<p class=\"has-luminous-vivid-amber-background-color has-background\"><strong>\u0628\u0631\u0627\u06cc \u062f\u06cc\u062f\u0646 \u0627\u06cc\u0646 \u0648\u06cc\u062f\u0626\u0648 \u062d\u062a\u0645\u0627 \u0627\u0632 \u0641\u06cc\u0644\u062a\u0631 \u0634\u06a9\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f . \u0628\u0631\u0627\u06cc \u062d\u0645\u0627\u06cc\u062a \u0645\u0627  \u0648\u0627\u0631\u062f \u06a9\u0627\u0646\u0627\u0644 <a href=\"https:\/\/www.youtube.com\/archartstudio\" target=\"_blank\" rel=\"noreferrer noopener\">\u06cc\u0648\u062a\u06cc\u0648\u0628 <\/a>\u0645\u0627 \u0634\u0648\u06cc\u062f \u0648 \u0627\u06cc\u0646 \u06a9\u0627\u0646\u0627\u0644 \u0631\u0627 subscribe \u06a9\u0646\u06cc\u062f<\/strong>.<\/p>\n\n\n\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/F4_lPNQhf0E\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n\n\n\n<h2 class=\"wp-block-heading\">\u0628\u0644\u0627\u06a9 \u062f\u0627\u06cc\u0646\u0627\u0645\u06cc\u06a9 \u0686\u06cc\u0633\u062a \u061f<\/h2>\n\n\n\n<p>\u062a\u0648\u06cc <a href=\"https:\/\/archart.ir\/Course\/1\/%D8%A2%D9%85%D9%88%D8%B2%D8%B4-%D8%B5%D9%81%D8%B1-%D8%AA%D8%A7-%D8%B5%D8%AF-%D9%86%D8%B1%D9%85-%D8%A7%D9%81%D8%B2%D8%A7%D8%B1-%D8%A7%D8%AA%D9%88%DA%A9%D8%AF-%D8%AF%D9%88-%D8%A8%D8%B9%D8%AF%DB%8C\/\">\u0627\u062a\u0648\u06a9\u062f<\/a> \u0627\u06cc\u0646 \u0627\u0645\u06a9\u0627\u0646 \u0628\u0631\u0627\u06cc \u0645\u0627 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u0647 \u06a9\u0647 \u0628\u062a\u0648\u0646\u06cc\u0645 \u0628\u0644\u0627\u06a9 \u0647\u0627\u06cc \u067e\u0648\u06cc\u0627\u06cc\u06cc \u0631\u0627 \u0628\u0648\u062c\u0648\u062f \u0628\u06cc\u0627\u0648\u0631\u06cc\u0645 \u062a\u0627 \u0628\u0627 \u062a\u063a\u06cc\u06cc\u0631 \u067e\u0627\u0631\u0627\u0645\u062a\u0631 \u0647\u0627\u06cc \u0622\u0646 \u0628\u062a\u0648\u0627\u0646\u06cc\u0645 \u0648\u06cc\u0698\u06af\u06cc \u0647\u0627\u06cc \u0628\u0644\u0627\u06a9 \u0631\u0627 \u062a\u063a\u06cc\u06cc\u0631 \u062f\u0647\u06cc\u0645.<\/p>\n\n\n\n<p>\u06cc\u0639\u0646\u06cc \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0646\u0645\u0648\u0646\u0647 \u06cc\u06a9 \u062f\u0631\u0628 \u0631\u0627 \u062a\u0635\u0648\u0631 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0634\u0645\u0627 \u0645\u06cc \u062e\u0648\u0627\u0647\u06cc\u062f \u062c\u0647\u062a \u0647\u0627\u06cc \u062f\u0631 \u0648 \u0647\u0645\u06cc\u0646\u0637\u0648\u0631 \u0628\u0632\u0631\u06af \u0648 \u06a9\u0648\u0686\u06a9 \u0634\u062f\u0646 \u0622\u0646 \u0628\u0647 \u0635\u0648\u0631\u062a \u062f\u0627\u06cc\u0646\u0627\u0645\u06cc\u06a9 \u062f\u0631 \u0628\u06cc\u0627\u062f \u0641\u0642\u0637 \u06a9\u0627\u0641\u06cc\u0647 \u06a9\u0647 \u0645\u0637\u0627\u0628\u0642 \u0622\u0645\u0648\u0632\u0634 \u0628\u0627\u0644\u0627 \u062f\u0631\u0628 \u0631\u0627 \u0628\u0647 \u0635\u0648\u0631\u062a \u062f\u0627\u06cc\u0646\u0627\u06a9 \u062f\u0631 \u0628\u06cc\u0627\u0648\u0631\u06cc\u062f.<\/p>\n\n\n\n<p>\u06cc\u0627 \u0645\u062b\u0644\u0627 \u062a\u0635\u0648\u0631 \u06a9\u0646 \u06a9\u0647 \u0634\u0645\u0627 \u0646\u0645\u06cc \u062f\u0627\u0646\u06cc \u0686\u0647 \u062a\u0639\u062f\u0627\u062f \u0635\u0646\u062f\u0644\u06cc \u062f\u0631 \u06cc\u06a9 \u0641\u0636\u0627\u06cc \u0633\u0627\u0644\u0646 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u06a9\u0646\u0627\u0631 \u0647\u0645 \u0642\u0631\u0627\u0631 \u0628\u06af\u06cc\u0631\u062f , \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u062f\u0627\u06cc\u0646\u0627\u0645\u06cc\u06a9 \u0628\u0644\u0627\u06a9 \u0634\u0645\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f\u06cc \u0635\u0646\u062f\u0644\u06cc \u0647\u0627\u06cc \u062f\u0627\u0644\u062e\u0644 \u0633\u0627\u0644\u0646 \u0631\u0627 \u0628\u0647 \u0635\u0648\u0631\u062a \u0627\u062a\u0648\u0645\u0627\u062a\u06cc\u06a9 \u0648 \u062f\u0627\u06cc\u0646\u0627\u0645\u06cc\u06a9 \u062f\u0631 \u0641\u0636\u0627 \u0628\u0647 \u0641\u0627\u0635\u0644\u0647 \u0647\u0627\u06cc \u0645\u0646\u0627\u0633\u0628 \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u062f.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u0633\u0627\u062e\u062a \u062f\u0627\u06cc\u0646\u0627\u0645\u06cc\u06a9 \u0628\u0644\u0627\u06a9 \u0627\u062a\u0648\u06a9\u062f \u06a9\u0627\u0631 \u0633\u0627\u062f\u0647 \u0627\u06cc \u0627\u0633\u062a \u061f<\/h2>\n\n\n\n<p>\u062e\u0644\u0627\u0635\u0647 \u0628\u062e\u0648\u0627\u0645 \u0628\u06af\u0645 \u062c\u0648\u0627\u0628 \u0628\u0644\u0647 \u0627\u0633\u062a \u0627\u0645\u0627 \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646 \u06a9\u0647 \u0628\u062e\u0648\u0627\u0647\u06cc\u062f \u0628\u0644\u0627\u06a9 \u0647\u0627\u06cc \u062f\u0627\u06cc\u0646\u0627\u0645\u06cc\u06a9\u06cc \u0628\u0627 \u0648\u06cc\u0698\u06af\u06cc \u0647\u0627\u06cc \u0645\u0648\u0631\u062f \u0646\u0638\u0631  \u0628\u0633\u0627\u0632\u06cc\u062f \u0646\u06cc\u0627\u0632 \u0627\u0633\u062a \u06a9\u0647 \u0627\u0648\u0644 \u0645\u0646\u0637\u0642 \u0648\u06cc\u062f\u0626\u0648 \u0628\u0627\u0644\u0627 \u0631\u0627 \u062f\u0631\u06a9 \u062a\u0627 \u062f\u0631 \u0646\u0647\u0627\u06cc\u062a \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0644\u0627\u06a9 \u0647\u0627\u06cc \u062f\u0627\u06cc\u0646\u0627\u0645\u06cc\u06a9 \u0627\u062a\u0648\u06a9\u062f \u06cc \u0645\u0646\u0627\u0633\u0628\u06cc \u0631\u0627 \u0628\u0633\u0627\u0632\u06cc\u062f.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u06cc\u06a9\u06cc \u0627\u0632 \u0648\u06cc\u0698\u06af\u06cc \u0647\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u062f\u0631 \u0627\u062a\u0648\u06a9\u062f , \u0633\u0627\u062e\u062a \u062f\u0627\u06cc\u0646\u0627\u0645\u06cc\u06a9 \u0628\u0644\u0627\u06a9 \u0627\u0633\u062a \u06a9\u0647 \u062a\u0648\u06cc \u0627\u06cc\u0646 \u0622\u0645\u0648\u0632\u0634 \u0628\u0647 \u0634\u0645\u0627 \u06cc\u0627\u062f \u0645\u06cc \u062f\u0647\u06cc\u0645 \u0686\u0637\u0648\u0631 \u0628\u0644\u0627\u06a9 \u0647\u0627\u06cc&#8230;<\/p>\n","protected":false},"author":2,"featured_media":3154,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,9],"tags":[3352,3356,3354,3353,3355],"class_list":["post-3152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2","category---autocad","tag-3352","tag-3356","tag-3354","tag-3353","tag-3355"],"amp_enabled":false,"acf":[],"_links":{"self":[{"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/posts\/3152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/comments?post=3152"}],"version-history":[{"count":0,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/posts\/3152\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/media\/3154"}],"wp:attachment":[{"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/media?parent=3152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/categories?post=3152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archart.ir\/blog\/wp-json\/wp\/v2\/tags?post=3152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}